{"id":8229,"date":"2024-12-18T14:43:56","date_gmt":"2024-12-18T14:43:56","guid":{"rendered":"http:\/\/dev-dug.flywheelsites.com\/politica-de-privacidad\/"},"modified":"2025-04-01T17:39:52","modified_gmt":"2025-04-01T17:39:52","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/dug.org\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#373737&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb5\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_highlighted_text text_color=\u00bb#ffffff\u00bb scribble_color=\u00bb#d1eb2f\u00bb style=\u00bbscribble\u00bb scribble_thickness=\u00bbthin\u00bb scribble_speed=\u00bb1.3s\u00bb scribble_easing=\u00bbease_in_out\u00bb text_direction=\u00bbdefault\u00bb]\n<h1>Aviso de privacidad<\/h1>\n<p>\u00daltima actualizaci\u00f3n 11 de noviembre de 2021<\/p>\n[\/nectar_highlighted_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb30px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (<strong>\u00abEmpresa<\/strong>\u00ab,<strong>\u00abnosotros<\/strong>\u00ab,<strong>\u00abnos<\/strong>\u00bb o<strong>\u00abnuestro<\/strong>\u00ab). Nos comprometemos a proteger tu informaci\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\u00e1cticas en relaci\u00f3n con tus datos personales, ponte en contacto con nosotros en dirt@dug.org.  <\/p>\n<p>Este aviso de privacidad describe c\u00f3mo podr\u00edamos utilizar tu informaci\u00f3n si t\u00fa:<\/p>\n<ul>\n<li aria-level=\"1\">Visita nuestro sitio web en <a href=\"https:\/\/dug.org\/\">https:\/\/dug.org<\/a><\/li>\n<li aria-level=\"1\">Participar con nosotros de otras formas relacionadas, como ventas, marketing o eventos.<\/li>\n<\/ul>\n<p>En este aviso de privacidad, si nos referimos a:<\/p>\n<ul>\n<li aria-level=\"1\"><strong>\u00abSitio web<\/strong>\u00ab, nos referimos a cualquier sitio web nuestro que haga referencia o enlace a esta pol\u00edtica<\/li>\n<li aria-level=\"1\"><strong>\u00abServicios<\/strong>\u00ab, nos referimos a nuestro Sitio Web y a otros servicios relacionados, incluyendo cualquier venta, marketing o evento<\/li>\n<\/ul>\n<p>El objetivo de este aviso de privacidad es explicarte de la forma m\u00e1s clara posible qu\u00e9 informaci\u00f3n recopilamos, c\u00f3mo la utilizamos y qu\u00e9 derechos tienes en relaci\u00f3n con ella. Si hay alg\u00fan t\u00e9rmino de este aviso de privacidad con el que no est\u00e9s de acuerdo, deja de utilizar nuestros Servicios inmediatamente. <\/p>\n<p><strong>Lee atentamente este aviso de privacidad, ya que te ayudar\u00e1 a comprender lo que hacemos con la informaci\u00f3n que recopilamos.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>\u00cdndice<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<ol>\n<li><a href=\"#infocollect\"><span style=\"font-weight: 400;\">  \u00bfQu\u00e9 informaci\u00f3n recogemos?<\/span><\/a><\/li>\n<li><a href=\"#infouse\"><span style=\"font-weight: 400;\">  \u00bfC\u00f3mo utilizamos tu informaci\u00f3n?<\/span><\/a><\/li>\n<li><a href=\"#infoshare\"><span style=\"font-weight: 400;\">  \u00bfSe compartir\u00e1 tu informaci\u00f3n con alguien?<\/span><\/a><\/li>\n<li><a href=\"#cookies\"><span style=\"font-weight: 400;\">  \u00bfUtilizamos cookies y otras tecnolog\u00edas de seguimiento?<\/span><\/a><\/li>\n<li><a href=\"#inforetain\"><span style=\"font-weight: 400;\">  \u00bfCu\u00e1nto tiempo conservamos tus datos?<\/span><\/a><\/li>\n<li><a href=\"#infosafe\"><span style=\"font-weight: 400;\">  \u00bfC\u00f3mo mantenemos segura tu informaci\u00f3n?<\/span><\/a><\/li>\n<li><a href=\"#infominors\"><span style=\"font-weight: 400;\">  \u00bfRecogemos informaci\u00f3n de menores?<\/span><\/a><\/li>\n<li><a href=\"#privacyrights\"><span style=\"font-weight: 400;\">  \u00bfCu\u00e1les son tus derechos de privacidad?<\/span><\/a><\/li>\n<li><a href=\"#DNT\"><span style=\"font-weight: 400;\">  Controles de las funciones No Seguir<\/span><\/a><\/li>\n<li><a href=\"#caresidents\"><span style=\"font-weight: 400;\">  \u00bfTienen los residentes en California derechos espec\u00edficos de privacidad?<\/span><\/a><\/li>\n<li><a href=\"#policyupdates\"><span style=\"font-weight: 400;\">  \u00bfRealizamos actualizaciones de este aviso?<\/span><\/a><\/li>\n<li><a href=\"#contactnotice\"><span style=\"font-weight: 400;\">  \u00bfC\u00f3mo puedes ponerte en contacto con nosotros acerca de este Aviso?<\/span><\/a><\/li>\n<li><a href=\"#request\"><span style=\"font-weight: 400;\">  \u00bfC\u00f3mo puedes revisar, actualizar o eliminar los datos que recopilamos de ti?<\/span><\/a><\/li>\n<\/ol>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbinfocollect\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>1. \u00bfQu\u00e9 informaci\u00f3n recogemos?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h3>Informaci\u00f3n personal que nos revelas<\/h3>\n<p><strong>En pocas palabras: <em>Recogemos la informaci\u00f3n personal que nos proporcionas.<\/em><\/strong><\/p>\n<p>Recogemos informaci\u00f3n personal que nos proporcionas voluntariamente cuando expresas tu inter\u00e9s en obtener informaci\u00f3n sobre nosotros o nuestros productos y Servicios, cuando participas en actividades en el Sitio Web o cuando te pones en contacto con nosotros.<\/p>\n<p>La informaci\u00f3n personal que recopilamos depende del contexto de tus interacciones con nosotros y con el Sitio Web, de las elecciones que hagas y de los productos y funciones que utilices. La informaci\u00f3n personal que recopilamos puede incluir lo siguiente: <\/p>\n<p><strong>Informaci\u00f3n personal proporcionada por ti.<\/strong>  Recogemos nombres, n\u00fameros de tel\u00e9fono, direcciones de correo electr\u00f3nico, direcciones postales, nombres de usuario, contrase\u00f1as, preferencias de contacto, direcciones de facturaci\u00f3n y otra informaci\u00f3n similar.<\/p>\n<p>Toda la informaci\u00f3n personal que nos proporciones debe ser verdadera, completa y exacta, y debes notificarnos cualquier cambio en dicha informaci\u00f3n personal.<\/p>\n<h3>Informaci\u00f3n recogida autom\u00e1ticamente<\/h3>\n<p><strong>En resumen: <em>Cierta informaci\u00f3n -como tu direcci\u00f3n de Protocolo de Internet (IP) y\/o las caracter\u00edsticas de tu navegador y dispositivo- se recopila autom\u00e1ticamente cuando visitas nuestro Sitio Web.<\/em><\/strong><\/p>\n<p>Recogemos autom\u00e1ticamente cierta informaci\u00f3n cuando visitas, utilizas o navegas por el Sitio Web. Esta informaci\u00f3n no revela tu identidad espec\u00edfica (como tu nombre o informaci\u00f3n de contacto), pero puede incluir informaci\u00f3n del dispositivo y de uso, como tu direcci\u00f3n IP, caracter\u00edsticas del navegador y del dispositivo, sistema operativo, preferencias de idioma, URL de referencia, nombre del dispositivo, pa\u00eds, ubicaci\u00f3n, informaci\u00f3n sobre c\u00f3mo y cu\u00e1ndo utilizas nuestro Sitio Web y otra informaci\u00f3n t\u00e9cnica. Esta informaci\u00f3n es necesaria principalmente para mantener la seguridad y el funcionamiento de nuestro Sitio Web, y para nuestros prop\u00f3sitos internos de an\u00e1lisis y elaboraci\u00f3n de informes.  <\/p>\n<p>Como muchas empresas, tambi\u00e9n recopilamos informaci\u00f3n a trav\u00e9s de cookies y tecnolog\u00edas similares.<\/p>\n<p>La informaci\u00f3n que recopilamos incluye:<\/p>\n<ul>\n<li aria-level=\"1\"><strong>Datos de registro y uso:<\/strong> Los datos de registro y uso son informaci\u00f3n relacionada con el servicio, el diagn\u00f3stico, el uso y el rendimiento que nuestros servidores recopilan autom\u00e1ticamente cuando accedes o utilizas nuestro Sitio Web y que registramos en archivos de registro. Dependiendo de c\u00f3mo interact\u00faes con nosotros, estos datos de registro pueden incluir tu direcci\u00f3n IP, informaci\u00f3n del dispositivo, tipo y configuraci\u00f3n del navegador e informaci\u00f3n sobre tu actividad en el Sitio Web (como las marcas de fecha\/hora asociadas a tu uso, p\u00e1ginas y archivos vistos, b\u00fasquedas y otras acciones que realices, como qu\u00e9 funciones utilizas), informaci\u00f3n de eventos del dispositivo (como actividad del sistema, informes de errores (a veces llamados \u00abcrash dumps\u00bb) y configuraci\u00f3n del hardware). <\/li>\n<li aria-level=\"1\"><strong>Datos del dispositivo:<\/strong> Recopilamos datos del dispositivo, como informaci\u00f3n sobre tu ordenador, tel\u00e9fono, tableta u otro dispositivo que utilices para acceder al Sitio Web. Dependiendo del dispositivo utilizado, estos datos del dispositivo pueden incluir informaci\u00f3n como tu direcci\u00f3n IP (o servidor proxy), n\u00fameros de identificaci\u00f3n del dispositivo y de la aplicaci\u00f3n, ubicaci\u00f3n, tipo de navegador, modelo de hardware proveedor de servicios de Internet y\/o operador de telefon\u00eda m\u00f3vil, sistema operativo e informaci\u00f3n de configuraci\u00f3n del sistema. <\/li>\n<li aria-level=\"1\"><strong>Datos de localizaci\u00f3n:<\/strong> Recogemos datos de localizaci\u00f3n, como informaci\u00f3n sobre la ubicaci\u00f3n de tu dispositivo, que puede ser precisa o imprecisa. La cantidad de informaci\u00f3n que recopilamos depende del tipo y la configuraci\u00f3n del dispositivo que utilizas para acceder al Sitio Web. Por ejemplo, podemos utilizar GPS y otras tecnolog\u00edas para recopilar datos de geolocalizaci\u00f3n que nos indican tu ubicaci\u00f3n actual (bas\u00e1ndose en tu direcci\u00f3n IP). Puedes optar por no permitirnos recopilar esta informaci\u00f3n rechazando el acceso a la informaci\u00f3n o desactivando la configuraci\u00f3n de Localizaci\u00f3n en tu dispositivo. Sin embargo, ten en cuenta que si optas por excluirte, es posible que no puedas utilizar determinados aspectos de los Servicios.    <\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbinfouse\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>2. \u00bfC\u00f3mo utilizamos tu informaci\u00f3n?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>En resumen: <em>procesamos tu informaci\u00f3n con fines basados en intereses comerciales leg\u00edtimos, el cumplimiento de nuestro contrato contigo, el cumplimiento de nuestras obligaciones legales y\/o tu consentimiento.<\/em><\/strong><\/p>\n<p>Utilizamos la informaci\u00f3n personal recogida a trav\u00e9s de nuestro Sitio Web para una serie de fines empresariales que se describen a continuaci\u00f3n. Procesamos tu informaci\u00f3n personal para estos fines bas\u00e1ndonos en nuestros intereses comerciales leg\u00edtimos, para celebrar o ejecutar un contrato contigo, con tu consentimiento y\/o para cumplir con nuestras obligaciones legales. A continuaci\u00f3n, junto a cada finalidad, indicamos los motivos espec\u00edficos de tratamiento en los que nos basamos.  <\/p>\n<p>Utilizamos la informaci\u00f3n que recogemos o recibimos:<\/p>\n<ul>\n<li aria-level=\"1\"><strong>Para facilitar la creaci\u00f3n de la cuenta y el proceso de inicio de sesi\u00f3n.  <\/strong>Si decides vincular tu cuenta con nosotros a una cuenta de terceros (como tu cuenta de Google o Facebook), utilizamos la informaci\u00f3n que nos permitiste recopilar de esos terceros para facilitar la creaci\u00f3n de la cuenta y el proceso de inicio de sesi\u00f3n para la ejecuci\u00f3n del contrato.<\/li>\n<li aria-level=\"1\"><strong>Para publicar testimonios.<\/strong>  Publicamos testimonios en nuestro Sitio Web que pueden contener informaci\u00f3n personal. Antes de publicar un testimonio, obtendremos tu consentimiento para utilizar tu nombre y el contenido del testimonio. Si deseas actualizar o eliminar tu testimonio, ponte en contacto con nosotros en dirt@dug.org y aseg\u00farate de incluir tu nombre, la ubicaci\u00f3n del testimonio y la informaci\u00f3n de contacto.  <\/li>\n<li aria-level=\"1\"><strong>Solicita opiniones.<\/strong>  Podemos utilizar tus datos para solicitarte opiniones y para ponernos en contacto contigo sobre tu uso de nuestro Sitio Web.<\/li>\n<li aria-level=\"1\"><strong>Para permitir las comunicaciones entre usuarios.<\/strong>  Podemos utilizar tu informaci\u00f3n para permitir las comunicaciones entre usuarios con el consentimiento de cada usuario.<\/li>\n<li aria-level=\"1\"><strong>Para gestionar las cuentas de usuario.<\/strong>  Podemos utilizar tu informaci\u00f3n para gestionar nuestra cuenta y mantenerla en funcionamiento.<\/li>\n<li aria-level=\"1\"><strong>Para enviarte informaci\u00f3n administrativa.<\/strong>  Podemos utilizar tus datos personales para enviarte informaci\u00f3n sobre productos, servicios y novedades y\/o informaci\u00f3n sobre cambios en nuestros t\u00e9rminos, condiciones y pol\u00edticas.<\/li>\n<li aria-level=\"1\"><strong>Para proteger nuestros Servicios.<\/strong>  Podemos utilizar tu informaci\u00f3n como parte de nuestros esfuerzos para mantener nuestro Sitio Web seguro y protegido (por ejemplo, para la supervisi\u00f3n y prevenci\u00f3n del fraude).<\/li>\n<li aria-level=\"1\"><strong>Para hacer cumplir nuestros t\u00e9rminos, condiciones y pol\u00edticas con fines comerciales, para cumplir con los requisitos legales y reglamentarios o en relaci\u00f3n con nuestro contrato.<\/strong><\/li>\n<li aria-level=\"1\"><strong>Para responder a solicitudes legales y evitar da\u00f1os.<\/strong>  Si recibimos una citaci\u00f3n u otra solicitud legal, es posible que tengamos que inspeccionar los datos que tenemos para determinar c\u00f3mo responder.<\/li>\n<li aria-level=\"1\"><strong>Cumple y gestiona tus pedidos.<\/strong>  Podemos utilizar tu informaci\u00f3n para cumplir y gestionar tus pedidos, pagos, devoluciones y cambios realizados a trav\u00e9s del Sitio Web.<\/li>\n<li aria-level=\"1\"><strong>Gestionar sorteos y concursos.<\/strong>  Podemos utilizar tus datos para administrar sorteos y concursos cuando decidas participar en nuestros concursos.<\/li>\n<li aria-level=\"1\"><strong>Para prestar y facilitar la prestaci\u00f3n de servicios al usuario.<\/strong>  Podemos utilizar tus datos para prestarte el servicio solicitado.<\/li>\n<li aria-level=\"1\"><strong>Responder a las consultas de los usuarios\/ofrecer apoyo a los usuarios.<\/strong>  Podemos utilizar tu informaci\u00f3n para responder a tus consultas y resolver cualquier posible problema que puedas tener con el uso de nuestros Servicios.<\/li>\n<li aria-level=\"1\"><strong>Para enviarte comunicaciones promocionales y de marketing.<\/strong>  Nosotros y\/o nuestros socios de marketing externos podemos utilizar la informaci\u00f3n personal que nos env\u00edes para nuestros fines de marketing, si esto se ajusta a tus preferencias de marketing. Por ejemplo, cuando expreses inter\u00e9s en obtener informaci\u00f3n sobre nosotros o nuestro Sitio Web, te suscribas a marketing o te pongas en contacto con nosotros de cualquier otra forma, recopilaremos informaci\u00f3n personal tuya. Puedes darte de baja de nuestros correos electr\u00f3nicos de marketing en cualquier momento (consulta la secci\u00f3n<a href=\"https:\/\/dug.org\/privacy-policy\/#privacyrights\">\u00ab\u00bfCU\u00c1LES SON TUS DERECHOS DE PRIVACIDAD?<\/a>\u00bb m\u00e1s abajo).  <\/li>\n<li aria-level=\"1\"><strong>Ofrecerte publicidad personalizada.<\/strong>  Podemos utilizar tu informaci\u00f3n para desarrollar y mostrar contenidos y publicidad personalizados (y trabajar con terceros que lo hagan) adaptados a tus intereses y\/o ubicaci\u00f3n y para medir su eficacia.<\/li>\n<li aria-level=\"1\"><strong>Para otros fines empresariales.<\/strong>  Podemos utilizar tu informaci\u00f3n para otros fines empresariales, como el an\u00e1lisis de datos, la identificaci\u00f3n de tendencias de uso, la determinaci\u00f3n de la eficacia de nuestras campa\u00f1as promocionales y para evaluar y mejorar nuestro Sitio Web, productos, marketing y tu experiencia. Podemos utilizar y almacenar esta informaci\u00f3n de forma agregada y an\u00f3nima para que no est\u00e9 asociada a usuarios finales individuales y no incluya informaci\u00f3n personal. <\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbinfoshare\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>3. \u00bfSe compartir\u00e1 tu informaci\u00f3n con alguien?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>En resumen: <\/strong> <em>S\u00f3lo compartimos informaci\u00f3n con tu consentimiento, para cumplir las leyes, prestarte servicios, proteger tus derechos o cumplir obligaciones comerciales.<\/em><\/p>\n<p>Podemos procesar o compartir los datos que tenemos sobre ti bas\u00e1ndonos en los siguientes fundamentos jur\u00eddicos:<\/p>\n<ul>\n<li aria-level=\"1\"><strong>Consentimiento: <\/strong>Podemos procesar tus datos si nos has dado tu consentimiento espec\u00edfico para utilizar tu informaci\u00f3n personal para un fin concreto.<\/li>\n<li aria-level=\"1\"><strong>Intereses leg\u00edtimos: <\/strong>Podemos tratar tus datos cuando sea razonablemente necesario para lograr nuestros intereses comerciales leg\u00edtimos.<\/li>\n<li aria-level=\"1\"><strong>Cumplimiento de un contrato:<\/strong> Cuando hayamos celebrado un contrato contigo, podremos tratar tus datos personales para cumplir los t\u00e9rminos de nuestro contrato.<\/li>\n<li aria-level=\"1\"><strong>Obligaciones legales: <\/strong>Podemos revelar tu informaci\u00f3n cuando estemos legalmente obligados a hacerlo para cumplir con la legislaci\u00f3n aplicable, las solicitudes gubernamentales, un procedimiento judicial, una orden judicial o un proceso legal, como en respuesta a una orden judicial o una citaci\u00f3n (incluida la respuesta a las autoridades p\u00fablicas para cumplir con los requisitos de seguridad nacional o de aplicaci\u00f3n de la ley).<\/li>\n<li aria-level=\"1\"><strong>Intereses vitales:<\/strong> Podemos revelar tu informaci\u00f3n cuando creamos que es necesario investigar, prevenir o tomar medidas en relaci\u00f3n con posibles infracciones de nuestras pol\u00edticas, sospechas de fraude, situaciones que impliquen amenazas potenciales para la seguridad de cualquier persona y actividades ilegales, o como prueba en litigios en los que estemos implicados.<\/li>\n<\/ul>\n<p><strong>M\u00e1s concretamente, puede que necesitemos procesar tus datos o compartir tu informaci\u00f3n personal en las siguientes situaciones:<\/strong><\/p>\n<ul>\n<li aria-level=\"1\"><strong>Traspasos de empresas.<\/strong>  Podemos compartir o transferir tu informaci\u00f3n en relaci\u00f3n con, o durante las negociaciones de, cualquier fusi\u00f3n, venta de activos de la empresa, financiaci\u00f3n o adquisici\u00f3n de todo o parte de nuestro negocio a otra empresa.<\/li>\n<li aria-level=\"1\"><strong>API de la plataforma Google Maps.<\/strong>  Podemos compartir tu informaci\u00f3n con determinadas API de Google Maps Platform (por ejemplo, Google Maps API, Place API). Para obtener m\u00e1s informaci\u00f3n sobre la Pol\u00edtica de Privacidad de Google, consulta este <a href=\"https:\/\/policies.google.com\/privacy\">enlace<\/a>. Obtenemos y almacenamos en tu dispositivo (\u00abcach\u00e9\u00bb) tu ubicaci\u00f3n. Puedes revocar tu consentimiento en cualquier momento poni\u00e9ndote en contacto con nosotros a trav\u00e9s de los datos de contacto que figuran al final de este documento.   <\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbcookies\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>4. \u00bfUtilizamos cookies y otras tecnolog\u00edas de seguimiento?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>En breve:<\/strong>  <em>Podemos utilizar cookies y otras tecnolog\u00edas de seguimiento para recopilar y almacenar tu informaci\u00f3n.<\/em><\/p>\n<p>Podemos utilizar cookies y tecnolog\u00edas de seguimiento similares (como balizas web y p\u00edxeles) para acceder o almacenar informaci\u00f3n. En nuestro Aviso sobre cookies encontrar\u00e1s informaci\u00f3n espec\u00edfica sobre c\u00f3mo utilizamos dichas tecnolog\u00edas y c\u00f3mo puedes rechazar determinadas cookies.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbinforetain\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>5. \u00bfCu\u00e1nto tiempo conservamos tus datos?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>En breve: <em> <\/em><\/strong><em>Conservamos tus datos durante el tiempo necesario para cumplir los fines descritos en este aviso de privacidad, a menos que la ley disponga lo contrario.<\/em><\/p>\n<p>S\u00f3lo conservaremos tus datos personales durante el tiempo que sea necesario para los fines establecidos en este aviso de privacidad, a menos que la ley exija o permita un periodo de conservaci\u00f3n m\u00e1s largo (como requisitos fiscales, contables u otros requisitos legales). Ninguna finalidad de este aviso requerir\u00e1 que conservemos tu informaci\u00f3n personal durante m\u00e1s de 2 a\u00f1os. <\/p>\n<p>Cuando ya no tengamos ninguna necesidad comercial leg\u00edtima de procesar tu informaci\u00f3n personal, eliminaremos o anonimizaremos dicha informaci\u00f3n o, si esto no es posible (por ejemplo, porque tu informaci\u00f3n personal se ha almacenado en archivos de copia de seguridad), almacenaremos de forma segura tu informaci\u00f3n personal y la aislaremos de cualquier procesamiento posterior hasta que sea posible eliminarla.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbinfosafe\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>6. \u00bfC\u00f3mo mantenemos segura tu informaci\u00f3n?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>En breve:<\/strong>  <em>Nuestro objetivo es proteger tu informaci\u00f3n personal mediante un sistema de medidas de seguridad organizativas y t\u00e9cnicas.<\/em><\/p>\n<p>Hemos implementado medidas de seguridad t\u00e9cnicas y organizativas apropiadas dise\u00f1adas para proteger la seguridad de cualquier informaci\u00f3n personal que procesemos. Sin embargo, a pesar de nuestras salvaguardas y esfuerzos por asegurar tu informaci\u00f3n, no se puede garantizar que ninguna transmisi\u00f3n electr\u00f3nica por Internet o tecnolog\u00eda de almacenamiento de informaci\u00f3n sea segura al 100%, por lo que no podemos prometer ni garantizar que los piratas inform\u00e1ticos, ciberdelincuentes u otros terceros no autorizados no puedan burlar nuestra seguridad y recopilar, acceder, robar o modificar indebidamente tu informaci\u00f3n. Aunque haremos todo lo posible para proteger tu informaci\u00f3n personal, la transmisi\u00f3n de informaci\u00f3n personal hacia y desde nuestro Sitio Web corre por tu cuenta y riesgo. S\u00f3lo debes acceder al Sitio Web dentro de un entorno seguro.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbinfominors\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>7. \u00bfRecogemos informaci\u00f3n de menores?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<em><strong>En resumen: <\/strong> No recopilamos conscientemente datos de menores de 18 a\u00f1os ni comercializamos con ellos.<\/em><\/p>\n<p>No solicitamos conscientemente datos de menores de 18 a\u00f1os ni comercializamos con ellos. Al utilizar el Sitio Web, declaras que tienes al menos 18 a\u00f1os o que eres el padre, la madre o el tutor de dicho menor y das tu consentimiento para que dicho menor dependiente utilice el Sitio Web. Si nos enteramos de que se han recogido datos personales de usuarios menores de 18 a\u00f1os, desactivaremos la cuenta y tomaremos medidas razonables para eliminar r\u00e1pidamente dichos datos de nuestros registros. Si tienes conocimiento de que hemos recopilado datos de menores de 18 a\u00f1os, ponte en contacto con nosotros en dirt@dug.org.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbprivacy rights\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>8. \u00bfCu\u00e1les son tus derechos de privacidad?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>En breve: <\/strong> <em>Puedes revisar, modificar o cancelar tu cuenta en cualquier momento.<\/em><\/p>\n<p>Si resides en el EEE o en el Reino Unido y crees que estamos tratando ilegalmente tus datos personales, tambi\u00e9n tienes derecho a presentar una reclamaci\u00f3n ante la autoridad supervisora de protecci\u00f3n de datos de tu pa\u00eds. Puedes encontrar sus datos de contacto aqu\u00ed: <a href=\"https:\/\/ec.europa.eu\/justice\/data-protection\/bodies\/authorities\/index_en.htm\">https:\/\/ec.europa.eu\/justice\/data-protection\/bodies\/authorities\/index_en.htm.<\/a> <\/p>\n<p>Si resides en Suiza, los datos de contacto de las autoridades de protecci\u00f3n de datos est\u00e1n disponibles aqu\u00ed: <a href=\"https:\/\/www.edoeb.admin.ch\/edoeb\/en\/home.html\">https:\/\/www.edoeb.admin.ch\/edoeb\/en\/home.html.<\/a><\/p>\n<p><strong>Cookies y tecnolog\u00edas similares:<\/strong> La mayor\u00eda de los navegadores Web est\u00e1n configurados para aceptar cookies por defecto. Si lo prefieres, normalmente puedes elegir configurar tu navegador para que elimine las cookies y las rechace. Si decides eliminar las cookies o rechazarlas, esto podr\u00eda afectar a determinadas funciones o servicios de nuestro Sitio Web. Para rechazar la publicidad basada en intereses de los anunciantes en nuestro Sitio Web, visita <a href=\"http:\/\/www.aboutads.info\/choices\/\">http:\/\/www.aboutads.info\/choices\/.<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbDNT\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>9. Controles de las funciones de no seguir<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]La mayor\u00eda de los navegadores web y algunos sistemas operativos y aplicaciones para m\u00f3viles incluyen una funci\u00f3n o ajuste de \u00abNo rastrear\u00bb (\u00abDo-Not-Track\u00bb, DNT) que puedes activar para se\u00f1alar tu preferencia de privacidad de que no se controlen ni recopilen datos sobre tus actividades de navegaci\u00f3n en l\u00ednea. En este momento no se ha finalizado ninguna norma tecnol\u00f3gica uniforme para reconocer e implementar las se\u00f1ales DNT. Por ello, actualmente no respondemos a las se\u00f1ales DNT del navegador ni a ning\u00fan otro mecanismo que comunique autom\u00e1ticamente tu elecci\u00f3n de no ser rastreado en l\u00ednea. Si se adopta una norma para el seguimiento en l\u00ednea que debamos seguir en el futuro, te informaremos sobre dicha pr\u00e1ctica en una versi\u00f3n revisada de este aviso de privacidad.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbcaresidents\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>10. \u00bfTienen los residentes en California derechos espec\u00edficos de privacidad?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>Resumiendo: <\/strong><em>S\u00ed, si eres residente en California, se te conceden derechos espec\u00edficos en relaci\u00f3n con el acceso a tu informaci\u00f3n personal.<\/em><\/p>\n<p>El art\u00edculo 1798.83 del C\u00f3digo Civil de California, tambi\u00e9n conocido como la ley \u00abShine The Light\u00bb, permite a nuestros usuarios residentes en California solicitarnos y obtener, una vez al a\u00f1o y de forma gratuita, informaci\u00f3n sobre las categor\u00edas de informaci\u00f3n personal (si las hubiera) que hayamos revelado a terceros con fines de marketing directo y los nombres y direcciones de todos los terceros con los que hayamos compartido informaci\u00f3n personal en el a\u00f1o natural inmediatamente anterior. Si eres residente en California y deseas realizar dicha solicitud, env\u00edanosla por escrito utilizando la informaci\u00f3n de contacto que se indica a continuaci\u00f3n. <\/p>\n<p>Si eres menor de 18 a\u00f1os, resides en California y tienes una cuenta registrada en el Sitio Web, tienes derecho a solicitar la eliminaci\u00f3n de los datos no deseados que publiques en el Sitio Web. Para solicitar la eliminaci\u00f3n de dichos datos, ponte en contacto con nosotros utilizando la informaci\u00f3n de contacto que se proporciona a continuaci\u00f3n, e incluye la direcci\u00f3n de correo electr\u00f3nico asociada a tu cuenta y una declaraci\u00f3n de que resides en California. Nos aseguraremos de que los datos no se muestren p\u00fablicamente en el Sitio Web, pero ten en cuenta que es posible que los datos no se eliminen completa o exhaustivamente de todos nuestros sistemas (por ejemplo, copias de seguridad, etc.).[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbcontactnotice\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>11. \u00bfRealizamos actualizaciones de este Aviso?  <span style=\"font-weight: 400;\">   <\/span><span style=\"font-weight: 400;\"> <\/span><\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>En breve:<\/strong>  <em>S\u00ed, actualizaremos este aviso cuando sea necesario para seguir cumpliendo las leyes pertinentes.<\/em><\/p>\n<p>Podemos actualizar este aviso de privacidad de vez en cuando. La versi\u00f3n actualizada se indicar\u00e1 mediante una fecha de \u00abRevisado\u00bb actualizada y la versi\u00f3n actualizada entrar\u00e1 en vigor tan pronto como sea accesible. Si realizamos cambios materiales en este aviso de privacidad, podremos notific\u00e1rtelo mediante la publicaci\u00f3n en un lugar destacado de un aviso de dichos cambios o envi\u00e1ndote directamente una notificaci\u00f3n. Te animamos a que revises este aviso de privacidad con frecuencia para estar informado de c\u00f3mo protegemos tu informaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbextra-color-3&#8243; custom_height=\u00bb1&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb50px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbrequest\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbjs\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>13. \u00bfC\u00f3mo puedes revisar, actualizar o eliminar los datos que recopilamos de ti?<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]En funci\u00f3n de las leyes aplicables en tu pa\u00eds, puedes tener derecho a solicitar el acceso a la informaci\u00f3n personal que recopilamos sobre ti, a modificar dicha informaci\u00f3n o a eliminarla en algunas circunstancias. Para solicitar la revisi\u00f3n, actualizaci\u00f3n o eliminaci\u00f3n de tu informaci\u00f3n personal, env\u00eda un formulario de solicitud haciendo clic <a href=\"https:\/\/app.termly.io\/notify\/00019b38-6713-404c-9304-6b56670fa577\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#373737&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb top_padding_tablet=\u00bb10%\u00bb constrain_group_3=\u00bbyes\u00bb bottom_padding_tablet=\u00bb10%\u00bb top_padding_phone=\u00bb15%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb15%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-8229","page","type-page","status-publish"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Aviso de privacidad \u00daltima actualizaci\u00f3n 11 de noviembre de 2021 Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (\u00abEmpresa\u00ab,\u00abnosotros\u00ab,\u00abnos\u00bb o\u00abnuestro\u00ab). Nos comprometemos a proteger tu informaci\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\u00e1cticas en relaci\u00f3n con\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/dug.org\/es\/politica-de-privacidad\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Denver Urban Gardens - Cultivating Food, Community, and Climate Resilience on a Human Scale\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad - Denver Urban Gardens\" \/>\n\t\t<meta property=\"og:description\" content=\"Aviso de privacidad \u00daltima actualizaci\u00f3n 11 de noviembre de 2021 Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (\u00abEmpresa\u00ab,\u00abnosotros\u00ab,\u00abnos\u00bb o\u00abnuestro\u00ab). Nos comprometemos a proteger tu informaci\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\u00e1cticas en relaci\u00f3n con\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dug.org\/es\/politica-de-privacidad\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-18T14:43:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-04-01T17:39:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreDUG\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pol\u00edtica de privacidad - Denver Urban Gardens\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Aviso de privacidad \u00daltima actualizaci\u00f3n 11 de noviembre de 2021 Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (\u00abEmpresa\u00ab,\u00abnosotros\u00ab,\u00abnos\u00bb o\u00abnuestro\u00ab). Nos comprometemos a proteger tu informaci\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\u00e1cticas en relaci\u00f3n con\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/politica-de-privacidad\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/politica-de-privacidad\\\/#listItem\",\"name\":\"Pol\\u00edtica de privacidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/politica-de-privacidad\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica de privacidad\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\",\"name\":\"Denver Urban Gardens\",\"description\":\"Cultivating Food, Community, and Climate Resilience on a Human Scale\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"email\":\"dirt@dug.org\",\"telephone\":\"+13032929900\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":15,\"maxValue\":25},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dug.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/DUG-horizontal-logo-1-2.png\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/politica-de-privacidad\\\/#organizationLogo\",\"width\":370,\"height\":130},\"image\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/politica-de-privacidad\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreDUG\",\"https:\\\/\\\/www.instagram.com\\\/denverurbangardens\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/denver-urban-gardens\"],\"address\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"1031 33rd St Ste 100, Ste 100\",\"postalCode\":\"80205-2743\",\"addressLocality\":\"Denver\",\"addressRegion\":\"Colorado\",\"addressCountry\":\"US\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/politica-de-privacidad\\\/#webpage\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/politica-de-privacidad\\\/\",\"name\":\"Pol\\u00edtica de privacidad - Denver Urban Gardens\",\"description\":\"Aviso de privacidad \\u00daltima actualizaci\\u00f3n 11 de noviembre de 2021 Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (\\u00abEmpresa\\u00ab,\\u00abnosotros\\u00ab,\\u00abnos\\u00bb o\\u00abnuestro\\u00ab). Nos comprometemos a proteger tu informaci\\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\\u00e1cticas en relaci\\u00f3n con\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/politica-de-privacidad\\\/#breadcrumblist\"},\"datePublished\":\"2024-12-18T14:43:56+00:00\",\"dateModified\":\"2025-04-01T17:39:52+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"name\":\"Denver Urban Gardens \\ud83c\\udf3f\",\"description\":\"Cultivating Food, Community, and Climate Resilience on a Human Scale\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pol\u00edtica de privacidad - Denver Urban Gardens<\/title>\n\n","aioseo_head_json":{"title":"Pol\u00edtica de privacidad - Denver Urban Gardens","description":"Aviso de privacidad \u00daltima actualizaci\u00f3n 11 de noviembre de 2021 Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (\u00abEmpresa\u00ab,\u00abnosotros\u00ab,\u00abnos\u00bb o\u00abnuestro\u00ab). Nos comprometemos a proteger tu informaci\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\u00e1cticas en relaci\u00f3n con","canonical_url":"https:\/\/dug.org\/es\/politica-de-privacidad\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/dug.org\/es\/politica-de-privacidad\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/dug.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/politica-de-privacidad\/#listItem","name":"Pol\u00edtica de privacidad"}},{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/politica-de-privacidad\/#listItem","position":2,"name":"Pol\u00edtica de privacidad","previousItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/dug.org\/es\/#organization","name":"Denver Urban Gardens","description":"Cultivating Food, Community, and Climate Resilience on a Human Scale","url":"https:\/\/dug.org\/es\/","email":"dirt@dug.org","telephone":"+13032929900","numberOfEmployees":{"@type":"QuantitativeValue","minValue":15,"maxValue":25},"logo":{"@type":"ImageObject","url":"https:\/\/dug.org\/wp-content\/uploads\/2026\/02\/DUG-horizontal-logo-1-2.png","@id":"https:\/\/dug.org\/es\/politica-de-privacidad\/#organizationLogo","width":370,"height":130},"image":{"@id":"https:\/\/dug.org\/es\/politica-de-privacidad\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/WeAreDUG","https:\/\/www.instagram.com\/denverurbangardens\/","https:\/\/www.linkedin.com\/company\/denver-urban-gardens"],"address":{"@id":"https:\/\/dug.org\/es\/#postaladdress","@type":"PostalAddress","streetAddress":"1031 33rd St Ste 100, Ste 100","postalCode":"80205-2743","addressLocality":"Denver","addressRegion":"Colorado","addressCountry":"US"}},{"@type":"WebPage","@id":"https:\/\/dug.org\/es\/politica-de-privacidad\/#webpage","url":"https:\/\/dug.org\/es\/politica-de-privacidad\/","name":"Pol\u00edtica de privacidad - Denver Urban Gardens","description":"Aviso de privacidad \u00daltima actualizaci\u00f3n 11 de noviembre de 2021 Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (\u00abEmpresa\u00ab,\u00abnosotros\u00ab,\u00abnos\u00bb o\u00abnuestro\u00ab). Nos comprometemos a proteger tu informaci\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\u00e1cticas en relaci\u00f3n con","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/dug.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/dug.org\/es\/politica-de-privacidad\/#breadcrumblist"},"datePublished":"2024-12-18T14:43:56+00:00","dateModified":"2025-04-01T17:39:52+00:00"},{"@type":"WebSite","@id":"https:\/\/dug.org\/es\/#website","url":"https:\/\/dug.org\/es\/","name":"Denver Urban Gardens \ud83c\udf3f","description":"Cultivating Food, Community, and Climate Resilience on a Human Scale","inLanguage":"es-ES","publisher":{"@id":"https:\/\/dug.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Denver Urban Gardens - Cultivating Food, Community, and Climate Resilience on a Human Scale","og:type":"article","og:title":"Pol\u00edtica de privacidad - Denver Urban Gardens","og:description":"Aviso de privacidad \u00daltima actualizaci\u00f3n 11 de noviembre de 2021 Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (\u00abEmpresa\u00ab,\u00abnosotros\u00ab,\u00abnos\u00bb o\u00abnuestro\u00ab). Nos comprometemos a proteger tu informaci\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\u00e1cticas en relaci\u00f3n con","og:url":"https:\/\/dug.org\/es\/politica-de-privacidad\/","og:image":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg","og:image:secure_url":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg","article:published_time":"2024-12-18T14:43:56+00:00","article:modified_time":"2025-04-01T17:39:52+00:00","article:publisher":"https:\/\/www.facebook.com\/WeAreDUG","twitter:card":"summary_large_image","twitter:title":"Pol\u00edtica de privacidad - Denver Urban Gardens","twitter:description":"Aviso de privacidad \u00daltima actualizaci\u00f3n 11 de noviembre de 2021 Gracias por elegir formar parte de nuestra comunidad en Denver Urban Gardens (\u00abEmpresa\u00ab,\u00abnosotros\u00ab,\u00abnos\u00bb o\u00abnuestro\u00ab). Nos comprometemos a proteger tu informaci\u00f3n personal y tu derecho a la privacidad. Si tienes alguna pregunta o duda sobre este aviso de privacidad o sobre nuestras pr\u00e1cticas en relaci\u00f3n con","twitter:image":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg"},"aioseo_meta_data":{"post_id":"8229","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 06:30:02","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2025-04-15 22:36:53","updated":"2026-05-13 06:30:02"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dug.org\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tPol\u00edtica de privacidad\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dug.org\/es\/"},{"label":"Pol\u00edtica de privacidad","link":"https:\/\/dug.org\/es\/politica-de-privacidad\/"}],"_links":{"self":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/pages\/8229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/comments?post=8229"}],"version-history":[{"count":0,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/pages\/8229\/revisions"}],"wp:attachment":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/media?parent=8229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}