{"id":6446,"date":"2012-08-17T00:00:00","date_gmt":"2012-08-17T00:00:00","guid":{"rendered":"http:\/\/dev-dug.flywheelsites.com\/huertos-comunitarios-y-hambre-primera-parte-2\/"},"modified":"2025-03-21T22:06:34","modified_gmt":"2025-03-21T22:06:34","slug":"huertos-comunitarios-y-hambre-primera-parte-2","status":"publish","type":"post","link":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/","title":{"rendered":"Huertos comunitarios y hambre: Primera parte"},"content":{"rendered":"<p>Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los alimentos y la comunidad est\u00e1n entrelazados a todos los niveles. Trabajamos para crear y compartir alimentos con nuestros vecinos, nos compadecemos cuando las cosechas fracasan y lo celebramos con fiestas de la cosecha y comidas populares.<\/p>\n<p>Dado el car\u00e1cter cotidiano y fundamental de la alimentaci\u00f3n, resulta sorprendente pensar que hay miembros de nuestra comunidad que no tienen suficiente para comer. De hecho, Hunger Free Colorado calcula que 815.000 habitantes de Colorado corren el riesgo de pasar hambre. Adem\u00e1s, m\u00e1s del 25% de las familias trabajadoras de Colorado no disponen de alimentos suficientes para cubrir sus necesidades b\u00e1sicas, y Colorado registra la tasa de pobreza infantil de m\u00e1s r\u00e1pido crecimiento del pa\u00eds.<\/p>\n<p>En la serie de Underground News sobre el hambre, exploraremos lo que significa pasar hambre en la tierra de la abundancia, los retos individuales y sist\u00e9micos que conducen a la inseguridad alimentaria de las familias trabajadoras, y el papel que desempe\u00f1an los huertos comunitarios en la mejora de la seguridad comunitaria y la mitigaci\u00f3n del hambre en los barrios.&nbsp;<\/p>\n<p>Empezamos esta serie con una nota positiva: el anuncio de una nueva iniciativa para conectar las despensas de alimentos con los huertos.&nbsp;<span style=\"color: black;\">En respuesta a la creciente demanda en las despensas de alimentos de la comunidad, varias organizaciones locales se han unido para crear Produce for Pantries. Denver Urban Gardens se une a Cooking Matters, Grow Local Colorado, Slow Food Denver, Plant a Row for The Hungry, Livewell Colorado, Food Bank of the Rockies, Metro CareRing, Yardharvest y St. John&#8217;s Cathedral para conectar las despensas de alimentos con los huertos escolares, los huertos comunitarios y los huertos dom\u00e9sticos de sus barrios para proporcionar alimentos saludables cultivados localmente y educaci\u00f3n nutricional a los necesitados. A trav\u00e9s de Yardharvest, las despensas de alimentos tambi\u00e9n estar\u00e1n conectadas con la fruta recogida de los \u00e1rboles de los residentes que tengan un excedente que quieran donar.<\/span><\/p>\n<p><span style=\"color: black;\">Hasta la fecha, veintitr\u00e9s despensas de la zona de Denver participan como centros piloto para 2012. El DUG, junto con nuestros socios de Slow Food Denver, est\u00e1 corriendo la voz entre los hortelanos de nuestras escuelas y huertos comunitarios de barrio, y el equipo de Produce for Pantries est\u00e1 llegando a los hortelanos dom\u00e9sticos a trav\u00e9s de una campa\u00f1a en los medios de comunicaci\u00f3n. Adem\u00e1s de recibir productos frescos, las despensas recibir\u00e1n recetas biling\u00fces f\u00e1ciles y nutritivas para acompa\u00f1ar los productos, informaci\u00f3n sobre la manipulaci\u00f3n y el almacenamiento seguros de los productos frescos, as\u00ed como clases de cocina in situ.<\/span><\/p>\n<p><span style=\"color: black;\"><span class=\"full-image-float-right ssNonEditable\"><span><img decoding=\"async\" style=\"width: 250px;\" data-src=\"\/storage\/web-graphics\/ProduceForPantries_RGB.jpg?__SQUARESPACE_CACHEVERSION=1345244860684\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/span><\/span>Produce for Pantries es una asociaci\u00f3n natural que adopta un enfoque comunitario de la seguridad alimentaria, garantizando que ning\u00fan producto se desperdicie y que los que tienen comida de sobra puedan ir directamente a quienes m\u00e1s la necesitan en su comunidad. Denver Urban Gardens agradece a sus socios su crucial labor en la lucha contra el hambre, as\u00ed como a los miles de <strong>horticultores<\/strong> del \u00e1rea de Denver <strong>que donan m\u00e1s de 30 toneladas de productos cada a\u00f1o<\/strong>.&nbsp;<\/span><\/p>\n<p><span style=\"color: black;\">Los jardineros comunitarios deben <strong><a href=\"https:\/\/dug.org\/es\/pongase-en-contacto-con-denver-urban-gardens\/\">ponerse en contacto<\/a> <\/strong>con nosotros para saber c\u00f3mo pueden participar, y los jardineros dom\u00e9sticos pueden enviar un correo electr\u00f3nico a produceforpantries@gmail.com&nbsp;a&nbsp;<span style=\"color: black;\">ponerse en contacto con la despensa de alimentos participante m\u00e1s cercana. Los residentes con \u00e1rboles frutales pueden cosechar con <a href=\"http:\/\/yardharvest.org\/\"><br \/>\n  <strong>Cosecha en el jard\u00edn<\/strong><br \/>\n<\/a><\/span><\/span><span style=\"color: black;\">&nbsp;para donar la fruta sobrante a las despensas cercanas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[42],"tags":[],"class_list":["post-6446","post","type-post","status-publish","format-standard","category-sin-categorizar"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"fmk_admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Denver Urban Gardens - Cultivating Food, Community, and Climate Resilience on a Human Scale\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens\" \/>\n\t\t<meta property=\"og:description\" content=\"Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-08-17T00:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-21T22:06:34+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreDUG\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#blogposting\",\"name\":\"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens\",\"headline\":\"Huertos comunitarios y hambre: Primera parte\",\"author\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/storage\\\/web-graphics\\\/ProduceForPantries_RGB.jpg?__SQUARESPACE_CACHEVERSION=1345244860684\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#articleImage\"},\"datePublished\":\"2012-08-17T00:00:00-06:00\",\"dateModified\":\"2025-03-21T22:06:34-06:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#webpage\"},\"articleSection\":\"Sin categorizar, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"position\":2,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/dug.org\\\/es\\\/category\\\/sin-categorizar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#listItem\",\"name\":\"Huertos comunitarios y hambre: Primera parte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#listItem\",\"position\":3,\"name\":\"Huertos comunitarios y hambre: Primera parte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\",\"name\":\"Denver Urban Gardens\",\"description\":\"Cultivating Food, Community, and Climate Resilience on a Human Scale\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"email\":\"dirt@dug.org\",\"telephone\":\"+13032929900\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":15,\"maxValue\":25},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dug.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/DUG-horizontal-logo-1-2.png\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#organizationLogo\",\"width\":370,\"height\":130},\"image\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreDUG\",\"https:\\\/\\\/www.instagram.com\\\/denverurbangardens\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/denver-urban-gardens\"],\"address\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"1031 33rd St Ste 100, Ste 100\",\"postalCode\":\"80205-2743\",\"addressLocality\":\"Denver\",\"addressRegion\":\"Colorado\",\"addressCountry\":\"US\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/\",\"name\":\"fmk_admin\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#webpage\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/\",\"name\":\"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens\",\"description\":\"Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\\u00e1s all\\u00e1 de su papel crucial como fuente de nutrici\\u00f3n y energ\\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/huertos-comunitarios-y-hambre-primera-parte-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"datePublished\":\"2012-08-17T00:00:00-06:00\",\"dateModified\":\"2025-03-21T22:06:34-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"name\":\"Denver Urban Gardens \\ud83c\\udf3f\",\"description\":\"Cultivating Food, Community, and Climate Resilience on a Human Scale\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens<\/title>\n\n","aioseo_head_json":{"title":"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens","description":"Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los","canonical_url":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#blogposting","name":"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens","headline":"Huertos comunitarios y hambre: Primera parte","author":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"publisher":{"@id":"https:\/\/dug.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"\/storage\/web-graphics\/ProduceForPantries_RGB.jpg?__SQUARESPACE_CACHEVERSION=1345244860684","@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#articleImage"},"datePublished":"2012-08-17T00:00:00-06:00","dateModified":"2025-03-21T22:06:34-06:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#webpage"},"isPartOf":{"@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#webpage"},"articleSection":"Sin categorizar, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/dug.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}},{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/category\/sin-categorizar\/#listItem","position":2,"name":"Sin categorizar","item":"https:\/\/dug.org\/es\/category\/sin-categorizar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#listItem","name":"Huertos comunitarios y hambre: Primera parte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#listItem","position":3,"name":"Huertos comunitarios y hambre: Primera parte","previousItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}}]},{"@type":"Organization","@id":"https:\/\/dug.org\/es\/#organization","name":"Denver Urban Gardens","description":"Cultivating Food, Community, and Climate Resilience on a Human Scale","url":"https:\/\/dug.org\/es\/","email":"dirt@dug.org","telephone":"+13032929900","numberOfEmployees":{"@type":"QuantitativeValue","minValue":15,"maxValue":25},"logo":{"@type":"ImageObject","url":"https:\/\/dug.org\/wp-content\/uploads\/2026\/02\/DUG-horizontal-logo-1-2.png","@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#organizationLogo","width":370,"height":130},"image":{"@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/WeAreDUG","https:\/\/www.instagram.com\/denverurbangardens\/","https:\/\/www.linkedin.com\/company\/denver-urban-gardens"],"address":{"@id":"https:\/\/dug.org\/es\/#postaladdress","@type":"PostalAddress","streetAddress":"1031 33rd St Ste 100, Ste 100","postalCode":"80205-2743","addressLocality":"Denver","addressRegion":"Colorado","addressCountry":"US"}},{"@type":"Person","@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author","url":"https:\/\/dug.org\/es\/author\/fmk_admin\/","name":"fmk_admin"},{"@type":"WebPage","@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#webpage","url":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/","name":"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens","description":"Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/dug.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/#breadcrumblist"},"author":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"creator":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"datePublished":"2012-08-17T00:00:00-06:00","dateModified":"2025-03-21T22:06:34-06:00"},{"@type":"WebSite","@id":"https:\/\/dug.org\/es\/#website","url":"https:\/\/dug.org\/es\/","name":"Denver Urban Gardens \ud83c\udf3f","description":"Cultivating Food, Community, and Climate Resilience on a Human Scale","inLanguage":"es-ES","publisher":{"@id":"https:\/\/dug.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Denver Urban Gardens - Cultivating Food, Community, and Climate Resilience on a Human Scale","og:type":"article","og:title":"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens","og:description":"Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los","og:url":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/","og:image":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg","og:image:secure_url":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg","article:published_time":"2012-08-17T00:00:00+00:00","article:modified_time":"2025-03-21T22:06:34+00:00","article:publisher":"https:\/\/www.facebook.com\/WeAreDUG","twitter:card":"summary_large_image","twitter:title":"Huertos comunitarios y hambre: Primera parte - Denver Urban Gardens","twitter:description":"Coles en la Granja Comunitaria DeLaney de DUG La comida es parte integrante de la experiencia humana. M\u00e1s all\u00e1 de su papel crucial como fuente de nutrici\u00f3n y energ\u00eda, la comida forma parte de casi todo lo que hacemos: nos reconforta y nos une. En nuestra vida cotidiana, y especialmente en un huerto comunitario, los","twitter:image":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg"},"aioseo_meta_data":{"post_id":"6446","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 02:46:11","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2025-04-16 04:43:34","updated":"2026-05-13 02:46:11","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dug.org\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dug.org\/es\/category\/sin-categorizar\/\" title=\"Sin categorizar\">Sin categorizar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tHuertos comunitarios y hambre: Primera parte\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dug.org\/es\/"},{"label":"Sin categorizar","link":"https:\/\/dug.org\/es\/category\/sin-categorizar\/"},{"label":"Huertos comunitarios y hambre: Primera parte","link":"https:\/\/dug.org\/es\/huertos-comunitarios-y-hambre-primera-parte-2\/"}],"_links":{"self":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts\/6446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/comments?post=6446"}],"version-history":[{"count":0,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts\/6446\/revisions"}],"wp:attachment":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/media?parent=6446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/categories?post=6446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/tags?post=6446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}