{"id":6870,"date":"2014-05-10T00:00:00","date_gmt":"2014-05-10T00:00:00","guid":{"rendered":"http:\/\/dev-dug.flywheelsites.com\/nuevo-jardin-destacado-escuela-primaria-samuels\/"},"modified":"2025-03-21T22:07:31","modified_gmt":"2025-03-21T22:07:31","slug":"nuevo-jardin-destacado-escuela-primaria-samuels","status":"publish","type":"post","link":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/","title":{"rendered":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels"},"content":{"rendered":"<div class=\"list-journal-entry-wrapper\">\n<div class=\"journal-entry-wrapper post-text authored-by-denverurbangardens \">\n<div id=\"item29960193\" class=\"journal-entry\">\n<div class=\"journal-entry-text\">\n<div class=\"journal-entry-tag journal-entry-tag-post-title\"><span class=\"posted-on\"> <img decoding=\"async\" class=\"inline-icon date-icon lazyload\" title=\"Fecha\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Fecha\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Viernes, Octubre 19, 2012 a las 1:05PM<\/span><\/div>\n<div class=\"body\">\n<p><em>Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias<\/em><\/p>\n<p><span class=\"full-image-float-right ssNonEditable\"><br \/>\n  <img decoding=\"async\" style=\"width: 300px;\" data-src=\"https:\/\/dug.org\/storage\/underground-photos\/2012%20-%20Samuels%20-%20Amparo%20and%20Janel%20with%20Tools%20Pallas%20Quist%20-%20LQ.jpg?__SQUARESPACE_CACHEVERSION=1350674227922\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><br \/>\n  <span class=\"thumbnail-caption\" style=\"width: 300px;\">Janel y Amparo, jardineras de Samuels <\/span><br \/>\n<\/span>En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que <em>educa a los ni\u00f1os de hoy para el mundo de ma\u00f1ana y capacita a los alumnos para el aprendizaje permanente<\/em>. Este a\u00f1o, en asociaci\u00f3n con Denver Urban Gardens, Samuels incorpor\u00f3 un huerto comunitario en la escuela para complementar esta misi\u00f3n y proporcionar un puente m\u00e1s fuerte entre el vecindario y la escuela.<\/p>\n<p>En mayo, tras meses de planificaci\u00f3n, padres, alumnos, profesores y vecinos se reunieron en la escuela primaria Samuels para celebrar su primera jornada de trabajo comunitario, un esfuerzo colectivo para construir juntos su huerto comunitario de cuarenta parcelas. Ese d\u00eda trascendental, el grupo rompi\u00f3 el suelo e inici\u00f3 el proceso de construcci\u00f3n de senderos y enmienda de la tierra con compost. Su objetivo era completar las cinco primeras camas comunitarias; superaron su objetivo y completaron nueve. La dedicaci\u00f3n de un grupo diverso de miembros de la comunidad y de la escuela, incluidos los estudiantes, lo hizo posible. Logros como \u00e9ste vinieron a definir su primera temporada de construcci\u00f3n y crecimiento en com\u00fan.<\/p>\n<p>Casi seis meses despu\u00e9s, cuando el huerto comunitario de la escuela primaria Samuels est\u00e1 terminando su primera temporada de cultivo, la escuela y la comunidad circundante pueden reflexionar sobre lo que el huerto comunitario aporta a su comunidad. Uno de los padres, Pallas Quist, se\u00f1ala,<\/p>\n<blockquote><p>T<span style=\"color: #222222;\">l jard\u00edn (incluso en su etapa de beb\u00e9) ha aportado belleza a un espacio antes desolado con sus colores vibrantes, sus acogedores girasoles, el verdor, el agua, la vida e incluso la actividad del jardinero ocasional trabajando en un exuberante huerto. Esa belleza afecta a los ojos de todos los miembros del personal y del alumnado del Samuels que pasan por all\u00ed cada d\u00eda. Me impresion\u00f3 personalmente la creatividad desplegada en cada parcela, y me complace formar parte de un grupo especial de jardineros que son personas incre\u00edbles.  <\/span><\/p><\/blockquote>\n<p><span style=\"color: #222222;\">Los comentarios de otros jardineros expresan sentimientos similares de orgullo por formar parte de algo que contribuye tan directa y positivamente a la vida de la escuela y del vecindario circundante. Jeff Harper, uno de los padres de Samuels, recuerda los progresos realizados: \u00abPensar que hace un a\u00f1o nuestro jard\u00edn no era m\u00e1s que un adefesio y un herbazal. Ver el progreso que nosotros, como escuela y como comunidad, hemos sido capaces de lograr en tan poco tiempo es nada menos que asombroso. Ver c\u00f3mo la comunidad, la escuela y las empresas locales se implican en el proyecto me ha aportado una enorme sensaci\u00f3n de logro y alegr\u00eda.\u00bb<\/span><\/p>\n<p><span style=\"color: #222222;\">Las asociaciones, el trabajo en equipo y un huerto inclusivo, que refleje la comunidad en la que se encuentra, son las se\u00f1as de identidad de un huerto comunitario pr\u00f3spero. El huerto comunitario de la escuela primaria Samuels ejemplifica estos valores y cualidades. Como informa alegremente Quist, \u00abtenemos una lista creciente de personas que se han apuntado para cultivar un huerto con nosotros la pr\u00f3xima primavera\u00bb.<\/span><\/p>\n<p><span style=\"color: #222222;\">Enhorabuena a Samuels por su incre\u00edble primera temporada cultivando juntos la comunidad y los alimentos. El sentido de comunidad que fomenta cada jardinero -ya sea padre, profesor, alumno o vecino- sigue contribuyendo a una comunidad m\u00e1s arraigada. En asociaci\u00f3n, esperamos con impaciencia 2013 y lo que nos deparar\u00e1 la temporada de cultivo.  <\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"journal-entry-tag journal-entry-tag-post-body\">\n<div class=\"journal-entry-tag-post-body-line1\"> <span class=\"posted-by\"> <a href=\"https:\/\/dug.org\/dug-blog\/author\/denverurbangardens\"> <img decoding=\"async\" class=\"inline-icon user-registered-icon lazyload\" title=\"Autor\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Autor\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Jardines urbanos de Denver<\/a><\/span> | <span class=\"post-comments\">Comentarios desactivados <\/span> en <span class=\"email-item\"><br \/>\n  <a href=\"https:\/\/dug.org\/dug-blog\/recommend\/29960193\"> <img decoding=\"async\" class=\"inline-icon email-icon lazyload\" title=\"Enviar art\u00edculo\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Enviar art\u00edculo\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Enviar art\u00edculo <\/a><br \/>\n<\/span> | <span class=\"share-item\"><br \/>\n  <a> <img decoding=\"async\" class=\"inline-icon share-icon lazyload\" title=\"Compartir art\u00edculo\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Compartir art\u00edculo\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Compartir post <\/a><br \/>\n<\/span> <\/div>\n<div class=\"journal-entry-tag-post-body-line2\"><span class=\"tagged-with\">etiquetado <span class=\"tag-element\"><br \/>\n  <a href=\"https:\/\/dug.org\/dug-blog\/tag\/the-underground-news\" rel=\"tag\"> <img decoding=\"async\" class=\"inline-icon tag-icon lazyload\" title=\"Etiqueta\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Etiqueta\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Noticias del metro<\/a><br \/>\n<\/span>, <span class=\"tag-element\"><br \/>\n  <a href=\"https:\/\/dug.org\/dug-blog\/tag\/community-garden-update\" rel=\"tag\"> <img decoding=\"async\" class=\"inline-icon tag-icon lazyload\" title=\"Etiqueta\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Etiqueta\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">huertos comunitarios<\/a><br \/>\n<\/span>, <span class=\"tag-element\"><br \/>\n  <a href=\"https:\/\/dug.org\/dug-blog\/tag\/school-gardens\" rel=\"tag\"> <img decoding=\"async\" class=\"inline-icon tag-icon lazyload\" title=\"Etiqueta\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Etiqueta\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">huertos escolares<\/a><br \/>\n<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[42],"tags":[],"class_list":["post-6870","post","type-post","status-publish","format-standard","category-sin-categorizar"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que educa a los ni\u00f1os de hoy para el mundo de ma\u00f1ana y capacita a los alumnos para el aprendizaje\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"fmk_admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Denver Urban Gardens - Cultivating Food, Community, and Climate Resilience on a Human Scale\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nuevo jard\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens\" \/>\n\t\t<meta property=\"og:description\" content=\"Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que educa a los ni\u00f1os de hoy para el mundo de ma\u00f1ana y capacita a los alumnos para el aprendizaje\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-05-10T00:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-21T22:07:31+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreDUG\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nuevo jard\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que educa a los ni\u00f1os de hoy para el mundo de ma\u00f1ana y capacita a los alumnos para el aprendizaje\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#blogposting\",\"name\":\"Nuevo jard\\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens\",\"headline\":\"Nuevo jard\\u00edn destacado: Escuela Primaria Samuels\",\"author\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dug.org\\\/universal\\\/images\\\/transparent.png\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#articleImage\"},\"datePublished\":\"2014-05-10T00:00:00-06:00\",\"dateModified\":\"2025-03-21T22:07:31-06:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#webpage\"},\"articleSection\":\"Sin categorizar, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"position\":2,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/dug.org\\\/es\\\/category\\\/sin-categorizar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#listItem\",\"name\":\"Nuevo jard\\u00edn destacado: Escuela Primaria Samuels\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#listItem\",\"position\":3,\"name\":\"Nuevo jard\\u00edn destacado: Escuela Primaria Samuels\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\",\"name\":\"Denver Urban Gardens\",\"description\":\"Cultivating Food, Community, and Climate Resilience on a Human Scale\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"email\":\"dirt@dug.org\",\"telephone\":\"+13032929900\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":15,\"maxValue\":25},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dug.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/DUG-horizontal-logo-1-2.png\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#organizationLogo\",\"width\":370,\"height\":130},\"image\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreDUG\",\"https:\\\/\\\/www.instagram.com\\\/denverurbangardens\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/denver-urban-gardens\"],\"address\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"1031 33rd St Ste 100, Ste 100\",\"postalCode\":\"80205-2743\",\"addressLocality\":\"Denver\",\"addressRegion\":\"Colorado\",\"addressCountry\":\"US\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/\",\"name\":\"fmk_admin\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#webpage\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/\",\"name\":\"Nuevo jard\\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens\",\"description\":\"Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que educa a los ni\\u00f1os de hoy para el mundo de ma\\u00f1ana y capacita a los alumnos para el aprendizaje\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/nuevo-jardin-destacado-escuela-primaria-samuels\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"datePublished\":\"2014-05-10T00:00:00-06:00\",\"dateModified\":\"2025-03-21T22:07:31-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"name\":\"Denver Urban Gardens \\ud83c\\udf3f\",\"description\":\"Cultivating Food, Community, and Climate Resilience on a Human Scale\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Nuevo jard\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens<\/title>\n\n","aioseo_head_json":{"title":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens","description":"Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que educa a los ni\u00f1os de hoy para el mundo de ma\u00f1ana y capacita a los alumnos para el aprendizaje","canonical_url":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#blogposting","name":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens","headline":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels","author":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"publisher":{"@id":"https:\/\/dug.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/dug.org\/universal\/images\/transparent.png","@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#articleImage"},"datePublished":"2014-05-10T00:00:00-06:00","dateModified":"2025-03-21T22:07:31-06:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#webpage"},"isPartOf":{"@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#webpage"},"articleSection":"Sin categorizar, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/dug.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}},{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/category\/sin-categorizar\/#listItem","position":2,"name":"Sin categorizar","item":"https:\/\/dug.org\/es\/category\/sin-categorizar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#listItem","name":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#listItem","position":3,"name":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels","previousItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}}]},{"@type":"Organization","@id":"https:\/\/dug.org\/es\/#organization","name":"Denver Urban Gardens","description":"Cultivating Food, Community, and Climate Resilience on a Human Scale","url":"https:\/\/dug.org\/es\/","email":"dirt@dug.org","telephone":"+13032929900","numberOfEmployees":{"@type":"QuantitativeValue","minValue":15,"maxValue":25},"logo":{"@type":"ImageObject","url":"https:\/\/dug.org\/wp-content\/uploads\/2026\/02\/DUG-horizontal-logo-1-2.png","@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#organizationLogo","width":370,"height":130},"image":{"@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/WeAreDUG","https:\/\/www.instagram.com\/denverurbangardens\/","https:\/\/www.linkedin.com\/company\/denver-urban-gardens"],"address":{"@id":"https:\/\/dug.org\/es\/#postaladdress","@type":"PostalAddress","streetAddress":"1031 33rd St Ste 100, Ste 100","postalCode":"80205-2743","addressLocality":"Denver","addressRegion":"Colorado","addressCountry":"US"}},{"@type":"Person","@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author","url":"https:\/\/dug.org\/es\/author\/fmk_admin\/","name":"fmk_admin"},{"@type":"WebPage","@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#webpage","url":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/","name":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens","description":"Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que educa a los ni\u00f1os de hoy para el mundo de ma\u00f1ana y capacita a los alumnos para el aprendizaje","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/dug.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/#breadcrumblist"},"author":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"creator":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"datePublished":"2014-05-10T00:00:00-06:00","dateModified":"2025-03-21T22:07:31-06:00"},{"@type":"WebSite","@id":"https:\/\/dug.org\/es\/#website","url":"https:\/\/dug.org\/es\/","name":"Denver Urban Gardens \ud83c\udf3f","description":"Cultivating Food, Community, and Climate Resilience on a Human Scale","inLanguage":"es-ES","publisher":{"@id":"https:\/\/dug.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Denver Urban Gardens - Cultivating Food, Community, and Climate Resilience on a Human Scale","og:type":"article","og:title":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens","og:description":"Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que educa a los ni\u00f1os de hoy para el mundo de ma\u00f1ana y capacita a los alumnos para el aprendizaje","og:url":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/","og:image":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg","og:image:secure_url":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg","article:published_time":"2014-05-10T00:00:00+00:00","article:modified_time":"2025-03-21T22:07:31+00:00","article:publisher":"https:\/\/www.facebook.com\/WeAreDUG","twitter:card":"summary_large_image","twitter:title":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels - Denver Urban Gardens","twitter:description":"Viernes, Octubre 19, 2012 a las 1:05PM Por Shannon Spurlock, Coordinadora de Iniciativas Comunitarias Janel y Amparo, jardineras de Samuels En el barrio Hampden South de Denver se encuentra la Escuela Primaria Samuels, un centro que educa a los ni\u00f1os de hoy para el mundo de ma\u00f1ana y capacita a los alumnos para el aprendizaje","twitter:image":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg"},"aioseo_meta_data":{"post_id":"6870","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 05:21:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2025-04-16 12:51:37","updated":"2026-05-13 05:21:19","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dug.org\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dug.org\/es\/category\/sin-categorizar\/\" title=\"Sin categorizar\">Sin categorizar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tNuevo jard\u00edn destacado: Escuela Primaria Samuels\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dug.org\/es\/"},{"label":"Sin categorizar","link":"https:\/\/dug.org\/es\/category\/sin-categorizar\/"},{"label":"Nuevo jard\u00edn destacado: Escuela Primaria Samuels","link":"https:\/\/dug.org\/es\/nuevo-jardin-destacado-escuela-primaria-samuels\/"}],"_links":{"self":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts\/6870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/comments?post=6870"}],"version-history":[{"count":0,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts\/6870\/revisions"}],"wp:attachment":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/media?parent=6870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/categories?post=6870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/tags?post=6870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}