{"id":7000,"date":"2014-05-10T00:00:00","date_gmt":"2014-05-10T00:00:00","guid":{"rendered":"http:\/\/dev-dug.flywheelsites.com\/ensalada-de-pasta-espanola-3\/"},"modified":"2025-03-21T22:07:47","modified_gmt":"2025-03-21T22:07:47","slug":"ensalada-de-pasta-espanola-3","status":"publish","type":"post","link":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/","title":{"rendered":"Ensalada de pasta espa\u00f1ola"},"content":{"rendered":"<div class=\"journal-entry-text\"><span class=\"posted-on\"><img decoding=\"async\" class=\"inline-icon date-icon lazyload\" title=\"Fecha\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Fecha\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">lunes, 16 de abril de 2012 a las 2:02PM<\/span><\/p>\n<div class=\"body\">\n<div class=\"adminLinkTableWrapper\">\n<table class=\"adminLinkTable\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td class=\"adminSegmentBoxBegin\" nowrap><\/td>\n<td class=\"adminSegmentBoxContent\" nowrap><span class=\"adminLinkWrapper\"><br \/>\n  <a>modificar<\/a><br \/>\n<\/span> <span class=\"adminLinkWrapper\"><br \/>\n  <a>eliminar<\/a><br \/>\n<\/span> <span class=\"adminLinkWrapper\"><br \/>\n  <a>organizar<\/a><br \/>\n<\/span> <span class=\"adminLinkWrapper\"><br \/>\n  <a>publicar seguimiento<\/a><br \/>\n<\/span><\/td>\n<td class=\"adminSegmentBoxEnd\" nowrap><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><strong>Raciones: 14<\/strong><\/p>\n<p><strong>Ingredientes<\/strong><br \/>\n<span style=\"color: #333333;\">4 tazas de macarrones de colores cocidos<br \/>\n<\/span><span style=\"color: #333333;\">1 1\/2 tazas de salsa, separada<br \/>\n<\/span><span style=\"color: #333333;\">1 taza de cebolla roja picada<br \/>\n<\/span><span style=\"color: #333333;\">2 tazas de tomate<br \/>\n<\/span><span style=\"color: #333333;\">1 taza de pimiento rojo picado<br \/>\n<\/span><span style=\"color: #333333;\">1 taza de pimiento verde picado<br \/>\n<\/span><span style=\"color: #333333;\">1 taza de alubias negras o rojas cocidas<br \/>\n<\/span><span style=\"color: #333333;\">1 taza de ma\u00edz cocido<br \/>\n<\/span><span style=\"color: #333333;\">1 cucharada de cilantro<\/span><\/p>\n<p><span style=\"color: #333333;\"><strong>Preparaci\u00f3n<br \/>\n<\/strong><\/span><span style=\"color: #333333;\">En un bol, mezcla los macarrones y 1\/2 taza de salsa. Dejar enfriar en el frigor\u00edfico durante 30 minutos y a\u00f1adir el resto de ingredientes. Refrigerar al menos 1 hora antes de servir.  <\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"journal-entry-tag-post-body-line1\"> <span class=\"posted-by\"> <a href=\"https:\/\/dug.org\/recipes\/author\/denverurbangardens\"> <img decoding=\"async\" class=\"inline-icon user-registered-icon lazyload\" title=\"Autor\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Autor\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Jardines urbanos de Denver<\/a><\/span> | <span class=\"post-comments\"><br \/>\n  <a href=\"https:\/\/dug.org\/recipes\/spanish-pasta-salad.html#comments\"> <img decoding=\"async\" class=\"inline-icon comment-icon lazyload\" title=\"Comentario\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Comentario\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Publicar un comentario<\/a><br \/>\n<\/span> | <span class=\"share-item\"><br \/>\n  <a> <img decoding=\"async\" class=\"inline-icon share-icon lazyload\" title=\"Compartir art\u00edculo\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Compartir art\u00edculo\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Compartir art\u00edculo <\/a><br \/>\n<\/span> <span class=\"email-item\"><br \/>\n  <a href=\"https:\/\/dug.org\/recipes\/recommend\/15870748\"> <img decoding=\"async\" class=\"inline-icon email-icon lazyload\" title=\"Enviar art\u00edculo\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Enviar art\u00edculo\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Enviar art\u00edculo <\/a><br \/>\n<\/span> <span class=\"print-item\"><br \/>\n  <a href=\"https:\/\/dug.org\/recipes\/spanish-pasta-salad.html?printerFriendly=true\"> <img decoding=\"async\" class=\"inline-icon print-icon lazyload\" title=\"Imprimir art\u00edculo\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Imprimir art\u00edculo\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">Imprimir art\u00edculo <\/a><br \/>\n<\/span> <\/div>\n<div class=\"journal-entry-tag-post-body-line2\"><span class=\"tagged-with\">etiquetado <span class=\"tag-element\"><br \/>\n  <a href=\"https:\/\/dug.org\/recipes\/tag\/corn\" rel=\"tag\"> <img decoding=\"async\" class=\"inline-icon tag-icon lazyload\" title=\"Etiqueta\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Etiqueta\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">ma\u00edz<\/a><br \/>\n<\/span>, <span class=\"tag-element\"><br \/>\n  <a href=\"https:\/\/dug.org\/recipes\/tag\/salad\" rel=\"tag\"> <img decoding=\"async\" class=\"inline-icon tag-icon lazyload\" title=\"Etiqueta\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Etiqueta\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">ensalada<\/a><br \/>\n<\/span>, <span class=\"tag-element\"><br \/>\n  <a href=\"https:\/\/dug.org\/recipes\/tag\/tomatoes\" rel=\"tag\"> <img decoding=\"async\" class=\"inline-icon tag-icon lazyload\" title=\"Etiqueta\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Etiqueta\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">tomates<\/a><br \/>\n<\/span>, <span class=\"tag-element\"><br \/>\n  <a href=\"https:\/\/dug.org\/recipes\/tag\/vegan\" rel=\"tag\"> <img decoding=\"async\" class=\"inline-icon tag-icon lazyload\" title=\"Etiqueta\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Etiqueta\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">vegano<\/a><br \/>\n<\/span>, <span class=\"tag-element\"><br \/>\n  <a href=\"https:\/\/dug.org\/recipes\/tag\/vegetarian\" rel=\"tag\"> <img decoding=\"async\" class=\"inline-icon tag-icon lazyload\" title=\"Etiqueta\" data-src=\"https:\/\/dug.org\/universal\/images\/transparent.png\" alt=\"Etiqueta\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">vegetariano<\/a><br \/>\n<\/span><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\/2 tazas de salsa, separada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7000","post","type-post","status-publish","format-standard","category-uncategorized"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\/2 tazas de salsa, separada 1 taza de cebolla roja picada 2 tazas de tomate 1 taza de pimiento rojo picado 1 taza de pimiento verde picado 1 taza de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"fmk_admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Denver Urban Gardens - Cultivating Food, Community, and Climate Resilience on a Human Scale\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ensalada de pasta espa\u00f1ola - Denver Urban Gardens\" \/>\n\t\t<meta property=\"og:description\" content=\"lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\/2 tazas de salsa, separada 1 taza de cebolla roja picada 2 tazas de tomate 1 taza de pimiento rojo picado 1 taza de pimiento verde picado 1 taza de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-05-10T00:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-21T22:07:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreDUG\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ensalada de pasta espa\u00f1ola - Denver Urban Gardens\" \/>\n\t\t<meta name=\"twitter:description\" content=\"lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\/2 tazas de salsa, separada 1 taza de cebolla roja picada 2 tazas de tomate 1 taza de pimiento rojo picado 1 taza de pimiento verde picado 1 taza de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#blogposting\",\"name\":\"Ensalada de pasta espa\\u00f1ola - Denver Urban Gardens\",\"headline\":\"Ensalada de pasta espa\\u00f1ola\",\"author\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dug.org\\\/universal\\\/images\\\/transparent.png\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#articleImage\"},\"datePublished\":\"2014-05-10T00:00:00-06:00\",\"dateModified\":\"2025-03-21T22:07:47-06:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#webpage\"},\"articleSection\":\"Uncategorized, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/dug.org\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#listItem\",\"name\":\"Ensalada de pasta espa\\u00f1ola\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#listItem\",\"position\":3,\"name\":\"Ensalada de pasta espa\\u00f1ola\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dug.org\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\",\"name\":\"Denver Urban Gardens\",\"description\":\"Cultivating Food, Community, and Climate Resilience on a Human Scale\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"email\":\"dirt@dug.org\",\"telephone\":\"+13032929900\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":15,\"maxValue\":25},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dug.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/DUG-horizontal-logo-1-2.png\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#organizationLogo\",\"width\":370,\"height\":130},\"image\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreDUG\",\"https:\\\/\\\/www.instagram.com\\\/denverurbangardens\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/denver-urban-gardens\"],\"address\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"1031 33rd St Ste 100, Ste 100\",\"postalCode\":\"80205-2743\",\"addressLocality\":\"Denver\",\"addressRegion\":\"Colorado\",\"addressCountry\":\"US\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/\",\"name\":\"fmk_admin\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e4ba6a155e1417426a5df305271fc0f0692e7bf416891cb009da27e67c8ad96?s=96&d=mm&r=g\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#webpage\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/\",\"name\":\"Ensalada de pasta espa\\u00f1ola - Denver Urban Gardens\",\"description\":\"lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\\\/2 tazas de salsa, separada 1 taza de cebolla roja picada 2 tazas de tomate 1 taza de pimiento rojo picado 1 taza de pimiento verde picado 1 taza de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/ensalada-de-pasta-espanola-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/author\\\/fmk_admin\\\/#author\"},\"datePublished\":\"2014-05-10T00:00:00-06:00\",\"dateModified\":\"2025-03-21T22:07:47-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dug.org\\\/es\\\/\",\"name\":\"Denver Urban Gardens \\ud83c\\udf3f\",\"description\":\"Cultivating Food, Community, and Climate Resilience on a Human Scale\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/dug.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ensalada de pasta espa\u00f1ola - Denver Urban Gardens<\/title>\n\n","aioseo_head_json":{"title":"Ensalada de pasta espa\u00f1ola - Denver Urban Gardens","description":"lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\/2 tazas de salsa, separada 1 taza de cebolla roja picada 2 tazas de tomate 1 taza de pimiento rojo picado 1 taza de pimiento verde picado 1 taza de","canonical_url":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#blogposting","name":"Ensalada de pasta espa\u00f1ola - Denver Urban Gardens","headline":"Ensalada de pasta espa\u00f1ola","author":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"publisher":{"@id":"https:\/\/dug.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/dug.org\/universal\/images\/transparent.png","@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#articleImage"},"datePublished":"2014-05-10T00:00:00-06:00","dateModified":"2025-03-21T22:07:47-06:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#webpage"},"isPartOf":{"@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#webpage"},"articleSection":"Uncategorized, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/dug.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/category\/uncategorized\/#listItem","name":"Uncategorized"}},{"@type":"ListItem","@id":"https:\/\/dug.org\/category\/uncategorized\/#listItem","position":2,"name":"Uncategorized","item":"https:\/\/dug.org\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#listItem","name":"Ensalada de pasta espa\u00f1ola"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#listItem","position":3,"name":"Ensalada de pasta espa\u00f1ola","previousItem":{"@type":"ListItem","@id":"https:\/\/dug.org\/category\/uncategorized\/#listItem","name":"Uncategorized"}}]},{"@type":"Organization","@id":"https:\/\/dug.org\/es\/#organization","name":"Denver Urban Gardens","description":"Cultivating Food, Community, and Climate Resilience on a Human Scale","url":"https:\/\/dug.org\/es\/","email":"dirt@dug.org","telephone":"+13032929900","numberOfEmployees":{"@type":"QuantitativeValue","minValue":15,"maxValue":25},"logo":{"@type":"ImageObject","url":"https:\/\/dug.org\/wp-content\/uploads\/2026\/02\/DUG-horizontal-logo-1-2.png","@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#organizationLogo","width":370,"height":130},"image":{"@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/WeAreDUG","https:\/\/www.instagram.com\/denverurbangardens\/","https:\/\/www.linkedin.com\/company\/denver-urban-gardens"],"address":{"@id":"https:\/\/dug.org\/es\/#postaladdress","@type":"PostalAddress","streetAddress":"1031 33rd St Ste 100, Ste 100","postalCode":"80205-2743","addressLocality":"Denver","addressRegion":"Colorado","addressCountry":"US"}},{"@type":"Person","@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author","url":"https:\/\/dug.org\/es\/author\/fmk_admin\/","name":"fmk_admin","image":{"@type":"ImageObject","url":"https:\/\/secure.gravatar.com\/avatar\/8e4ba6a155e1417426a5df305271fc0f0692e7bf416891cb009da27e67c8ad96?s=96&d=mm&r=g"}},{"@type":"WebPage","@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#webpage","url":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/","name":"Ensalada de pasta espa\u00f1ola - Denver Urban Gardens","description":"lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\/2 tazas de salsa, separada 1 taza de cebolla roja picada 2 tazas de tomate 1 taza de pimiento rojo picado 1 taza de pimiento verde picado 1 taza de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/dug.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/#breadcrumblist"},"author":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"creator":{"@id":"https:\/\/dug.org\/es\/author\/fmk_admin\/#author"},"datePublished":"2014-05-10T00:00:00-06:00","dateModified":"2025-03-21T22:07:47-06:00"},{"@type":"WebSite","@id":"https:\/\/dug.org\/es\/#website","url":"https:\/\/dug.org\/es\/","name":"Denver Urban Gardens \ud83c\udf3f","description":"Cultivating Food, Community, and Climate Resilience on a Human Scale","inLanguage":"es-ES","publisher":{"@id":"https:\/\/dug.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Denver Urban Gardens - Cultivating Food, Community, and Climate Resilience on a Human Scale","og:type":"article","og:title":"Ensalada de pasta espa\u00f1ola - Denver Urban Gardens","og:description":"lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\/2 tazas de salsa, separada 1 taza de cebolla roja picada 2 tazas de tomate 1 taza de pimiento rojo picado 1 taza de pimiento verde picado 1 taza de","og:url":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/","og:image":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg","og:image:secure_url":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg","article:published_time":"2014-05-10T00:00:00+00:00","article:modified_time":"2025-03-21T22:07:47+00:00","article:publisher":"https:\/\/www.facebook.com\/WeAreDUG","twitter:card":"summary_large_image","twitter:title":"Ensalada de pasta espa\u00f1ola - Denver Urban Gardens","twitter:description":"lunes, 16 de abril de 2012 a las 2:02PM modificar eliminar organizar publicar seguimiento Raciones: 14 Ingredientes 4 tazas de macarrones de colores cocidos 1 1\/2 tazas de salsa, separada 1 taza de cebolla roja picada 2 tazas de tomate 1 taza de pimiento rojo picado 1 taza de pimiento verde picado 1 taza de","twitter:image":"https:\/\/dug.org\/wp-content\/uploads\/2025\/07\/DUG23-007-1-scaled.jpg"},"aioseo_meta_data":{"post_id":"7000","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 05:34:37","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2025-04-16 12:55:59","updated":"2026-05-13 05:34:37"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dug.org\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dug.org\/category\/uncategorized\/\" title=\"Uncategorized\">Uncategorized<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tEnsalada de pasta espa\u00f1ola\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dug.org\/es\/"},{"label":"Uncategorized","link":"https:\/\/dug.org\/category\/uncategorized\/"},{"label":"Ensalada de pasta espa\u00f1ola","link":"https:\/\/dug.org\/es\/ensalada-de-pasta-espanola-3\/"}],"_links":{"self":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts\/7000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/comments?post=7000"}],"version-history":[{"count":0,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/posts\/7000\/revisions"}],"wp:attachment":[{"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/media?parent=7000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/categories?post=7000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dug.org\/es\/wp-json\/wp\/v2\/tags?post=7000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}